{"id":38060,"date":"2025-03-15T10:00:00","date_gmt":"2025-03-15T13:00:00","guid":{"rendered":"https:\/\/vopus.org\/reloj-auxiliar-del-angel-de-la-guarda\/"},"modified":"2025-03-23T17:29:09","modified_gmt":"2025-03-23T20:29:09","slug":"horloge-auxiliaire-de-l-ange-gardien","status":"publish","type":"post","link":"https:\/\/vopus.org\/fr\/horloge-auxiliaire-de-l-ange-gardien\/","title":{"rendered":"\u00ab\u00a0Horologium auxiliaris tutelaris angeli\u00a0\u00bb (Horloge auxiliaire de l&rsquo;Ange Gardien)"},"content":{"rendered":"\n<p>Bien-aim\u00e9s\/\u00e9es lecteurs\/trices :<\/p>\n\n\n\n<p>Je suis heureux de vous faire parvenir cette gravure qui appara\u00eet intitul\u00e9e dans un livre en latin sous le nom de&#8230;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><em>\u2026HOROLOGIUM AUXILIARIS TUTELARIS ANGELI<\/em><br>\u2500\u2018Reloj auxiliar del \u00c1ngel de la Guarda\u2019\u2500<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img decoding=\"async\" width=\"480\" height=\"900\" src=\"https:\/\/vopus.org\/wp-content\/uploads\/2025\/03\/reloj-auxiliar-del-angel-de-la-guarda-jeremias-drexel-480x900.jpg\" alt=\"Horloge auxiliaire de l'Ange Gardien, Jerem\u00edas Drexel\" class=\"wp-image-38024\" title=\"Horloge auxiliaire de l'Ange Gardien, Jerem\u00edas Drexel\" srcset=\"https:\/\/vopus.org\/wp-content\/uploads\/2025\/03\/reloj-auxiliar-del-angel-de-la-guarda-jeremias-drexel-480x900.jpg 480w, https:\/\/vopus.org\/wp-content\/uploads\/2025\/03\/reloj-auxiliar-del-angel-de-la-guarda-jeremias-drexel-960x1800.jpg 960w, https:\/\/vopus.org\/wp-content\/uploads\/2025\/03\/reloj-auxiliar-del-angel-de-la-guarda-jeremias-drexel-768x1440.jpg 768w, https:\/\/vopus.org\/wp-content\/uploads\/2025\/03\/reloj-auxiliar-del-angel-de-la-guarda-jeremias-drexel.jpg 458w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n<p>Ce livre a \u00e9t\u00e9 \u00e9crit par le j\u00e9suite allemand Jerem\u00edas Drexel \u2500 1581-1638 \u2500 et publi\u00e9 en 1631 \u00e0 Amsterdam. Le livre est \u00e9galement connu sous le titre <em>Le compagnon horaire du chr\u00e9tien d\u00e9vou\u00e9 : compos\u00e9 de saintes pri\u00e8res et de m\u00e9ditations divines<\/em>.<\/p>\n\n\n\n<p>Pour entrer dans l&rsquo;\u00e9tude de cette belle gravure, nous allons porter notre regard sur les nuages des cieux, et \u00e0 l&rsquo;int\u00e9rieur d&rsquo;eux apparaissent les mots h\u00e9breux faisant allusion au Cr\u00e9ateur <strong>IOD HE VAU HE<\/strong> qui \u2500 se traduit par J\u00c9HOVAH \u2500.<\/p>\n\n\n\n<p>Plus bas apparaissent les mots latins <strong><em>DISCE ORARE<\/em><\/strong> \u2500 traduction : \u2018apprends \u00e0 prier\u2019 \u2500.<\/p>\n\n\n\n<p>En dehors des nuages, nous observons deux autres mots latins : <strong><em>DISCE VIVERE<\/em><\/strong> \u2500 traduction : \u2018apprends \u00e0 vivre\u2019 \u2500.<\/p>\n\n\n\n<p>Au pied de l&rsquo;ange de notre gravure, nous pouvons voir une torche et une cruche d&rsquo;eau accompagn\u00e9es des mots latins <strong><em>DISCE MORI<\/em><\/strong> \u2500 traduction : \u2018apprends \u00e0 mourir\u2019 \u2500.<\/p>\n\n\n\n<p>Que signifie tout cela ?<\/p>\n\n\n\n<p>Il est incontestable que tous ceux qui essaient de vivre <strong>le Chemin Secret<\/strong> <strong>que nous enseigne la Gnose,<\/strong> doivent \u00eatre tr\u00e8s clairs sur la n\u00e9cessit\u00e9 imm\u00e9diate de <strong>savoir prier, savoir vivre et savoir mourir.<\/strong><\/p>\n\n\n\n<p>Les m\u00e9ditations ou r\u00e9flexions et pri\u00e8res de ce livre se concentrent sur trois choses fondamentales, comme le montre la gravure :<\/p>\n\n\n\n<p>Premi\u00e8rement : <strong>\u00ab apprendre \u00e0 mourir psychologiquement \u00bb<\/strong> \u00e0 travers, par exemple, des r\u00e9flexions sur la certitude de la mort mystique, ou sur la perte irr\u00e9parable du temps, ou sur la multitude de nos dettes karmiques. Quant \u00e0 cette question de <strong>savoir mourir<\/strong>, nombreux sont les \u00e9tudiants de la Gnose qui croient qu&rsquo;ils sont vraiment en train de mourir psychologiquement, mais en r\u00e9alit\u00e9 ils se font des illusions sur eux-m\u00eames. Pour mourir vraiment, il faut traverser beaucoup de crises \u00e9motionnelles, de souffrances volontaires, de sacrifices conscients, et ce ne sont pas des paroles ni des poses pi\u00e9tistes ni des douceurs feintes, non. La vraie mort int\u00e9rieure nous produira toujours de l&rsquo;amertume int\u00e9rieure, et nous ne pouvons pas tomber dans <strong>l&rsquo;autocompassion<\/strong> pour justifier notre tristesse ou nos pleurs. Les vrais martyrs de l&rsquo;antiquit\u00e9 qui ont embrass\u00e9 la <strong>mort mystique<\/strong>, pour comble, \u00e9taient toujours seuls, sans une petite main pour leur caresser l&rsquo;\u00e9paule ou leur promettre une vie meilleure&#8230;<\/p>\n\n\n\n<p>Deuxi\u00e8mement : d&rsquo;autre part, ces m\u00e9ditations du livre se concentrent sur <strong>\u00ab apprendre \u00e0 vivre \u00bb<\/strong> en m\u00e9ditant sur la patience, l&rsquo;ob\u00e9issance aux principes divins, la temp\u00e9rance, l&rsquo;humilit\u00e9, etc. <strong>Savoir vivre<\/strong> signifie \u00eatre toujours vigilant pour rester dans la <strong>FA\u00c7ON JUSTE D&rsquo;AGIR, LA FA\u00c7ON JUSTE DE SENTIR ET LA FA\u00c7ON JUSTE DE PENSER<\/strong>. Pour pouvoir mener \u00e0 bien cette t\u00e2che, il est indispensable de NE PAS NOUS OUBLIER DE NOUS-M\u00caMES \u00e0 aucun moment. Cela signifie rester, comme notre b\u00e9ni Gourou l&rsquo;exprimait si bien : \u00ab<strong> Comme la sentinelle en temps de guerre \u00bb<\/strong>. Nos paroles doivent \u00eatre m\u00e9dit\u00e9es avant d&rsquo;\u00eatre prononc\u00e9es, nos pens\u00e9es doivent \u00eatre examin\u00e9es avant de les prendre pour certaines et nos actions doivent co\u00efncider avec nos aspirations profondes de vouloir changer notre vie m\u00e9canique pour une vie CONSCIENTE.<\/p>\n\n\n\n<p>Troisi\u00e8mement : <strong>\u00ab Apprendre \u00e0 prier \u00bb<\/strong>, ce qui signifie parler avec notre Dieu interne. Pour savoir prier, il est n\u00e9cessaire que nous le fassions dans le TROISI\u00c8ME \u00c9TAT DE CONSCIENCE, en d&rsquo;autres termes, nos pri\u00e8res ne doivent jamais \u00eatre faites de mani\u00e8re m\u00e9canique. Lorsque nous prions m\u00e9caniquement \u2500 nous dit notre Patriarche Samael Aun Weor \u2500 nos agr\u00e9gats psychologiques prennent nos pri\u00e8res et les retournent contre nous-m\u00eames, de telle sorte que ce que nous \u00e9tions en train de demander deviendra quelque chose qui, justement, demandera le contraire de ce que nous souhaitons recevoir.&nbsp;<\/p>\n\n\n\n<p>Dans une section ci-dessous, nous trouvons les mots latins suivants :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00abHorologii ab Angelo directi Funiculus triplex;<br>\nVITA, VOTA, FATA.<br>\nTrahe VITAM Secundum Deum<br>\nTrahe VOTIS ad te Deum<br>\npost FATA traheris ad Deum\u00bb.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p><strong>Traduction<\/strong>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u2018Le triple c\u00e2ble de l&rsquo;horloge dirig\u00e9 par l&rsquo;ange nous dit :<br><strong>VIDA, VOTOS, HADO.<\/strong><br><strong><strong>La vie s&rsquo;\u00e9coule selon Dieu\u2019.<\/strong><\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>En d&rsquo;autres termes, essaye de faire co\u00efncider ta vie avec la volont\u00e9 de ton \u00caTRE R\u00c9EL.<\/p>\n\n\n\n<p><strong>&lsquo;Attire Dieu \u00e0 toi par les v\u0153ux\u2019.<\/strong><\/p>\n\n\n\n<p>Ou promesses, ce qui signifie que, ce que tu promets \u00e0 ton \u00caTRE INT\u00c9RIEUR, t\u00e2che de toujour de l\u2019accomplir. Mets en action le <em>thelema<\/em> \u2500 la volont\u00e9 \u2500 pour que tes v\u0153ux deviennent r\u00e9alit\u00e9. Ne te laisse pas entra\u00eener par la force mal\u00e9fique de l&rsquo;entropie.<\/p>\n\n\n\n<p><strong>\u2018Apr\u00e8s le sort [le destin], tu seras entra\u00een\u00e9 vers Dieu\u2019.<\/strong><\/p>\n\n\n\n<p>Certes, par la pers\u00e9v\u00e9rance, peu \u00e0 peu, la force m\u00eame de l&rsquo;\u00caTRE t&rsquo;attirera vers la Grande R\u00e9alit\u00e9. La rencontre avec notre P\u00e8re int\u00e9rieur est toujours le r\u00e9sultat de deux forces : une force centrifuge \u2500 celle que l&rsquo;\u00caTRE exerce de l&rsquo;int\u00e9rieur vers l&rsquo;ext\u00e9rieur \u2500 et une autre force centrip\u00e8te \u2500 celle que nous exercerons de l&rsquo;ext\u00e9rieur vers l&rsquo;int\u00e9rieur par la pri\u00e8re, les je\u00fbnes, les pratiques \u00e9sot\u00e9riques, la continuit\u00e9 de propos, etc., etc., etc. \u2500.<\/p>\n\n\n\n<p>L&rsquo;horloge que l&rsquo;ange nous montre nous indique que notre vie passe plus vite que nous ne le pensons. Nous avons \u00e9t\u00e9 envoy\u00e9s dans une \u00e9cole que nous appelons VIE et nous devons devenir conscients de notre court s\u00e9jour dans celle-ci.<\/p>\n\n\n\n<p>Les trois petits c\u00e2bles qui sont attach\u00e9s \u00e0 cette horloge indiquent pr\u00e9cis\u00e9ment ce qui a \u00e9t\u00e9 pr\u00e9c\u00e9demment mentionn\u00e9 et expliqu\u00e9 : <strong><em>VITA, VOTA, FATA<\/em><\/strong>, la vie, les v\u0153ux et les faits ou le destin.<\/p>\n\n\n\n<p>Il est \u00e9galement int\u00e9ressant de voir que ces trois cordes de l&rsquo;horloge de notre ange ont des terminaisons florales. Pourquoi ? Eh bien, pr\u00e9cis\u00e9ment, parce que l\u2019accomplissement de nos devoirs : savoir vivre, savoir prier et savoir mourir, nous donnera les fruits spirituels que nous aspirons \u00e0 trouver au cours de notre parcours.<\/p>\n\n\n\n<p>Il est \u00e9galement int\u00e9ressant de noter que TOUT PASSE, rien ne demeure. Les temps passent, les \u00e9poques passent, les modes passent, les amis passent, les ennemis passent, les saisons passent : printemps, \u00e9t\u00e9, automne et hiver, les gloires humaines passent, les passions passent, la beaut\u00e9 passe, la laideur passe, les mots passent, les honneurs passent, les buts humains passent, etc., etc., etc. Seul demeure celui qui A \u00c9T\u00c9, EST ET SERA, c\u2019est-\u00e0-dire, L\u2019\u00caTRE INT\u00c9RIEUR PROFOND.<\/p>\n\n\n\n<p>Avec ces mots, nous voulons \u00e9galement souligner que l\u2019eau qui jaillit du vase ou de l\u2019amphore que le pied de l\u2019ange pi\u00e9tine, et aussi la torche, toutes deux sur le sol, sont \u00e9galement passag\u00e8res, m\u00eame si elles ne le semblent pas.<\/p>\n\n\n\n<p>Le V.M. Samael nous a toujours parl\u00e9 de l&rsquo;une des parties autonomes et auto-conscientes appel\u00e9e notre Ange Gardien. Cette partie sacr\u00e9e de notre \u00caTRE R\u00c9EL veille toujours sur nous, cherchant \u00e0 chaque instant \u00e0 ce que nous valorisions chaque seconde de notre existence afin que nous ne perdions pas de temps pendant que nous vivons sur la face de notre monde. Telle est la figure centrale de notre gravure, et c&rsquo;est pourquoi nous le voyons signalant de sa main droite le Cr\u00e9ateur pr\u00e8s des mots h\u00e9bra\u00efques qui le d\u00e9finissent.&nbsp;<\/p>\n\n\n\n<p>Je vous offre maintenant quelques phrases pour votre r\u00e9flexion :<\/p>\n\n\n\n<p><strong><em>\u00ab La pri\u00e8re devrait \u00eatre la cl\u00e9 du jour et le verrou de la nuit \u00bb.<\/em><\/strong><br>Thomas Fuller<\/p>\n\n\n\n<p><strong><em>\u00ab Se conformer \u00e0 la volont\u00e9 de Dieu est la plus belle pri\u00e8re de l&rsquo;\u00e2me chr\u00e9tienne \u00bb.<\/em><\/strong><br>Saint Alphonse Marie de Liguori<\/p>\n\n\n\n<p><strong><em>\u00ab La vraie pri\u00e8re ne consiste pas \u00e0 se recueillir \u00e0 une heure donn\u00e9e pour prononcer des paroles orales ou mentales, mais c&rsquo;est une mani\u00e8re religieuse de tout faire, et ainsi on mange, on boit, on se prom\u00e8ne, on s&rsquo;amuse, on \u00e9crit, on travaille et on dort m\u00eame en priant ; tout est pri\u00e8re \u00bb.<\/em><\/strong><br>Unamuno<\/p>\n\n\n\n<p><strong><em>\u00ab Certaines pens\u00e9es sont comme des pri\u00e8res. \u00c0 certains moments, quelle que soit la posture du corps, l&rsquo;\u00e2me est \u00e0 genoux \u00bb.<\/em><\/strong><br>Victor Hugo<\/p>\n\n\n\n<p><strong><em>\u00ab L&rsquo;art et la science ne suffisent pas, mais la patience est \u00e9galement indispensable \u00bb.<\/em><\/strong><br>Goethe<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><em>TEMPORA MUTANTUR.<\/em><\/strong><br>\u2500 \u2018Les temps changent\u2019 \u2500.<\/p>\n\n\n\n<p><strong>KWEN KHAN KHU<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est incontestable que tous ceux qui essaient de vivre le Chemin Secret que nous enseigne la Gnose, doivent \u00eatre tr\u00e8s clairs sur la n\u00e9cessit\u00e9 imm\u00e9diate de savoir prier, savoir vivre et savoir mourir. <\/p>\n","protected":false},"author":4,"featured_media":38046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[477,147,212,467],"tags":[1022,819,886,1021],"contenido":[272],"fuente":[],"pilar":[],"fase":[],"conferencia":[],"read_online":[],"author_tax":[323],"class_list":["post-38060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-symboles-universels","category-vie-et-mort","category-mysticisme","category-messages-du-v-m-kwen-khan-khu","tag-mistica-3-fr","tag-oracion-fr","tag-misticismo-fr","tag-angeles-fr","contenido-articles","author_tax-v-m-kwen-khan-khu-fr"],"yoast_focuskw":"ange gardien","yoast_metadesc":"Tous ceux qui essaient de vivre le Chemin Secret doivent \u00eatre tr\u00e8s clairs sur la n\u00e9cessit\u00e9 de savoir prier, savoir vivre et savoir mourir. Ange gardien","_links":{"self":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts\/38060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/comments?post=38060"}],"version-history":[{"count":3,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts\/38060\/revisions"}],"predecessor-version":[{"id":38068,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts\/38060\/revisions\/38068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/media\/38046"}],"wp:attachment":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/media?parent=38060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/categories?post=38060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/tags?post=38060"},{"taxonomy":"contenido","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/contenido?post=38060"},{"taxonomy":"fuente","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/fuente?post=38060"},{"taxonomy":"pilar","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/pilar?post=38060"},{"taxonomy":"fase","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/fase?post=38060"},{"taxonomy":"conferencia","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/conferencia?post=38060"},{"taxonomy":"read_online","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/read_online?post=38060"},{"taxonomy":"author_tax","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/author_tax?post=38060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}