{"id":31685,"date":"2023-11-19T11:15:52","date_gmt":"2023-11-19T14:15:52","guid":{"rendered":"https:\/\/vopus.org\/el-extasis-de-santa-cecilia\/"},"modified":"2023-11-19T11:20:08","modified_gmt":"2023-11-19T14:20:08","slug":"l-extase-de-sainte-cecile","status":"publish","type":"post","link":"https:\/\/vopus.org\/fr\/l-extase-de-sainte-cecile\/","title":{"rendered":"L\u2019extase de sainte C\u00e9cile"},"content":{"rendered":"\n<p>Tr\u00e8s chers\/\u00e8res amis\/ies&nbsp;:<\/p>\n\n\n\n<p>Je me permets de vous envoyer cette \u0153uvre artistique cr\u00e9\u00e9e entre les ann\u00e9es 1483 et 1520 par l\u2019artiste italien et architecte nomm\u00e9 Raffaello Sanzio. Le titre qu\u2019elle porte est\u2026<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">\u2026L\u2019EXTASE DE SAINTE C\u00c9CILE<\/h2>\n\n\n\n<p>Pour entrer dans notre sujet, nous commencerons par dire que cette \u0153uvre se trouve dans la Pinacoth\u00e8que Nationale de Bologne, en Italie.<\/p>\n\n\n\n<p>Les historiens nous disent la chose suivante&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab C\u00e9cile de Rome, plus connue sous le nom de sainte C\u00e9cile, \u00e9tait une noble romaine convertie au Christianisme et martyris\u00e9e pour sa foi \u00e0 une date ind\u00e9termin\u00e9e, entre 180 et 350. Elle est consid\u00e9r\u00e9e comme la patronne de la musique sacr\u00e9e et, en son honneur, un important mouvement de renouveau de la musique sacr\u00e9e de la fin du XIXe si\u00e8cle re\u00e7ut le nom de c\u00e9cilianisme. Ses attributs sont l\u2019orgue, le luth et les roses.<\/em><\/p>\n\n\n\n<p><em>Dans le livre <\/em>Martyrologium hieronymianum, il est mentionn\u00e9&nbsp;: \u201cAppi\u00e2 vi\u00e2 in e\u00e2dem urbe Rom\u00e2 natale et passio s\u00e1nct\u00e6 Cec\u00edli\u00e6 virginia\u201d<em>, \u2018Dans la Voie Appienne de la ville de Rome, sainte C\u00e9cile, vierge, est n\u00e9e et morte\u2019&nbsp;\u00bb<\/em>.<\/p>\n<\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium is-resized\"><img decoding=\"async\" src=\"https:\/\/vopus.org\/wp-content\/uploads\/2023\/11\/el-extasis-de-santa-cecilia-raffaello-sanzio-480x739.jpg\" alt=\"L\u2019extase de sainte C\u00e9cile, Raffaello Sanzio\" class=\"wp-image-31658\" width=\"360\" height=\"554\" title=\"L\u2019extase de sainte C\u00e9cile, Raffaello Sanzio\" srcset=\"https:\/\/vopus.org\/wp-content\/uploads\/2023\/11\/el-extasis-de-santa-cecilia-raffaello-sanzio-480x739.jpg 480w, https:\/\/vopus.org\/wp-content\/uploads\/2023\/11\/el-extasis-de-santa-cecilia-raffaello-sanzio-960x1478.jpg 960w, https:\/\/vopus.org\/wp-content\/uploads\/2023\/11\/el-extasis-de-santa-cecilia-raffaello-sanzio-768x1182.jpg 768w, https:\/\/vopus.org\/wp-content\/uploads\/2023\/11\/el-extasis-de-santa-cecilia-raffaello-sanzio.jpg 602w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption class=\"wp-element-caption\"><em>L\u2019extase de sainte C\u00e9cile<\/em>, Raffaello Sanzio<\/figcaption><\/figure><\/div>\n\n\n<p>La peinture nous montre sainte C\u00e9cile, v\u00eatue d\u2019une belle robe dor\u00e9e, levant les yeux vers le ciel et tenant un orgue dans ses mains. L\u2019orgue \u00e9tait un instrument de musique tr\u00e8s v\u00e9n\u00e9r\u00e9 au Moyen \u00c2ge et \u00e0 la Renaissance car la musique que cet instrument produit est tr\u00e8s spirituelle.<\/p>\n\n\n\n<p>\u00c0 sa droite se trouve Jean l\u2019\u00c9vang\u00e9liste. N\u2019oublions pas que Jean repr\u00e9sente le verbe r\u00e9v\u00e9lateur.<\/p>\n\n\n\n<p>Nous voyons ensuite un aigle assis sur un livre ferm\u00e9, ce qui nous indique que les livres sacr\u00e9s ne peuvent \u00eatre interpr\u00e9t\u00e9s que par inspiration divine. Cette inspiration est indiqu\u00e9e par l\u2019aigle.<\/p>\n\n\n\n<p>\u00c0 c\u00f4t\u00e9 nous voyons l\u2019Ap\u00f4tre saint Paul s\u2019appuyant sur l\u2019\u00e9p\u00e9e, contemplant les instruments de musique pos\u00e9s \u00e0 ses pieds. On remarque que le violon est d\u00e9pourvu de cordes.<\/p>\n\n\n\n<p>\u00c0 gauche nous voyons Augustin d\u2019Hippone avec son b\u00e2ton \u2500 354-430 \u2500, premier philosophe important de l\u2019\u00e8re chr\u00e9tienne, \u00e9v\u00eaque d\u2019Hippone \u2500 une ville de l\u2019Alg\u00e9rie actuelle \u2500 pendant les derni\u00e8res ann\u00e9es de l\u2019Empire romain.<\/p>\n\n\n\n<p>Enfin, nous voyons Marie Madeleine tenant un flacon d\u2019alb\u00e2tre. Le fait que Marie Madeleine soit pr\u00e9sente dans cette repr\u00e9sentation picturale nous indique que tous les membres de cette \u0153uvre connaissaient <strong>l\u2019<em>ars<\/em> transmutatoire ou le secret que renferme l\u2019Arcane<\/strong> <strong>A<\/strong>.<strong>Z<\/strong>.<strong>F<\/strong>.<\/p>\n\n\n\n<p>D\u2019autre part, il est bon de noter que la simple ceinture de sainte C\u00e9cile \u00e9tait un symbole traditionnel de <strong>chastet\u00e9<\/strong> \u00e0 la renaissance.<\/p>\n\n\n\n<p>Dans la partie sup\u00e9rieure de cette repr\u00e9sentation artistique, nous pouvons observer des anges repr\u00e9sent\u00e9s comme des enfants, qui sont l\u2019inspiration per\u00e7ue par sainte C\u00e9cile pour \u00e9laborer ses chants sacr\u00e9s et ses mystique interpr\u00e9tations musicales.<\/p>\n\n\n\n<p>Permettez-moi d\u2019ajouter maintenant quelques phrases qui m\u00e9ritent notre r\u00e9flexion&nbsp;:<\/p>\n\n\n\n<p><strong><em>\u00ab\u00a0La tradition religieuse est l\u2019axe de diamant sur lequel tourne notre pass\u00e9\u00a0\u00bb.<\/em><\/strong><br>B\u00e9cquer<\/p>\n\n\n\n<p><strong><em>\u00ab\u00a0Le vrai devoir filial consiste \u00e0 r\u00e9aliser avec succ\u00e8s les travaux que nos parents n\u2019ont pas achev\u00e9s, et \u00e0 transmettre leurs conqu\u00eates \u00e0 la post\u00e9rit\u00e9\u00a0\u00bb.<\/em><\/strong><br>Confucius<\/p>\n\n\n\n<p><strong><em>\u00ab La tradition, mieux que tous les trait\u00e9s c\u00e9r\u00e9moniels et que le code des usages en vogue, indique la mani\u00e8re de s\u2019adapter aux circonstances. Seule la tradition ne s\u2019acqui\u00e8re pas\u00a0\u00bb.<\/em><\/strong><br>Rub\u00e9n Dar\u00edo<\/p>\n\n\n\n<p><strong><em>\u00ab\u00a0Les vrais hommes progressistes sont ceux qui ont pour point de d\u00e9part un respect profond du pass\u00e9\u00a0\u00bb.<\/em><\/strong><br>Ren\u00e1n<\/p>\n\n\n\n<p><strong><em>\u00ab\u00a0La personne la plus facile \u00e0 tromper et \u00e0 trahir est soi-m\u00eame\u00a0\u00bb.<\/em><\/strong><br>Lytton<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><em>CONDITIO SINE QUA NON<\/em><\/strong>.<br>\u2500 &lsquo;Condition sans laquelle rien n\u2019est possible&rsquo; \u2500.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>KWEN KHAN KHU<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La peinture nous montre sainte C\u00e9cile, v\u00eatue d\u2019une belle robe dor\u00e9e, levant les yeux vers le ciel et tenant un orgue dans ses mains. L\u2019orgue \u00e9tait un instrument de musique tr\u00e8s v\u00e9n\u00e9r\u00e9 au Moyen \u00c2ge et \u00e0 la Renaissance car la musique que cet instrument produit est tr\u00e8s spirituelle.<\/p>\n","protected":false},"author":4,"featured_media":31676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[477,212,467],"tags":[756,534,541],"contenido":[272],"fuente":[49],"pilar":[],"fase":[],"conferencia":[],"read_online":[],"author_tax":[323],"class_list":["post-31685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-symboles-universels","category-mysticisme","category-messages-du-v-m-kwen-khan-khu","tag-primeros-cristianos-fr","tag-arte-fr","tag-simbolismo-fr","contenido-articles","fuente-maestro","author_tax-v-m-kwen-khan-khu-fr"],"yoast_focuskw":"sainte C\u00e9cile","yoast_metadesc":"Sainte C\u00e9cile, v\u00eatue d\u2019une belle robe dor\u00e9e, levant les yeux vers le ciel et tenant un orgue dans ses mains. Raffaello Sanzio, L\u2019extase de sainte C\u00e9cile","_links":{"self":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts\/31685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/comments?post=31685"}],"version-history":[{"count":2,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts\/31685\/revisions"}],"predecessor-version":[{"id":31689,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/posts\/31685\/revisions\/31689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/media\/31676"}],"wp:attachment":[{"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/media?parent=31685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/categories?post=31685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/tags?post=31685"},{"taxonomy":"contenido","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/contenido?post=31685"},{"taxonomy":"fuente","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/fuente?post=31685"},{"taxonomy":"pilar","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/pilar?post=31685"},{"taxonomy":"fase","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/fase?post=31685"},{"taxonomy":"conferencia","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/conferencia?post=31685"},{"taxonomy":"read_online","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/read_online?post=31685"},{"taxonomy":"author_tax","embeddable":true,"href":"https:\/\/vopus.org\/fr\/wp-json\/wp\/v2\/author_tax?post=31685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}